{"id":22739,"date":"2025-09-22T23:10:47","date_gmt":"2025-09-22T21:10:47","guid":{"rendered":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/?p=22739"},"modified":"2025-09-22T23:10:47","modified_gmt":"2025-09-22T21:10:47","slug":"napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran","status":"publish","type":"post","link":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/2025\/09\/22\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\/","title":{"rendered":"Napoli-Pisa 3-2 (39&#8242; Gilmour, 60&#8242; Nzola, 73&#8242; Spinazzola, 82&#8242; Lucca, 90&#8242; Lorran)."},"content":{"rendered":"<p><strong>Il Napoli vince ma quanta sofferenza nel finale. Gli azzurri si prendono la vetta solitaria e allungano sulle avversarie. <\/strong><!--more--><\/p>\n<p><strong>Arriva una vittoria alla prima partita dopo il rientro in Champions. Per gli uomini di Conte decisive le reti di Gilmour, Spinazzola e Lucca. Quarta vittoria consecutiva contro un buon Pisa.<\/strong><\/p>\n<p><em><strong>97&#8242;\u00a0<\/strong><\/em><strong>Finisce qui! Il Napoli, non senza sofferenza, batte 3-2 il Pisa.<\/strong><\/p>\n<p><em><strong>92&#8242;\u00a0<\/strong><\/em>Fuorigioco del Pisa, che aveva creato un&#8217;altra occcasione pericolosa. Ancora tempestivo Meret.<\/p>\n<p><em><strong>91&#8242;\u00a0<\/strong><\/em>Grave errore di Di Lorenzo in disimpegno. Regala letteralmente il pallone al Pisa, gol di Lorran su assist di Angori.<\/p>\n<p><em><strong>90&#8242; &#8211;\u00a0<\/strong>6&#8242; di recupero<\/em><\/p>\n<p><strong>85&#8242;<\/strong>\u00a0Errore di Beukema, Tramoni vicino al 3-2.<\/p>\n<p><strong>82&#8242; GOOOOOOOOOOOOOOOOL! Primo gol di Lucca in maglia azzurra, conclusione potente sotto la traversa.<\/strong><\/p>\n<p><em><strong>82&#8242;<\/strong><\/em>\u00a0Giallo per Lusuardi per il fallo su Lucca.<\/p>\n<p><em><strong>81&#8242;<\/strong><\/em>\u00a0Problema muscolare per Buongiorno, al suo posto entra Juan Jesus.<\/p>\n<p><em><strong>80&#8242;\u00a0<\/strong><\/em>Fuori Marin, dentro Lorran.<\/p>\n<p><em><strong>77&#8242;<\/strong><\/em>\u00a0Fuori Hojlund, dentro Lucca.<\/p>\n<p><em><strong>75&#8242;<\/strong><\/em>\u00a0Fuori Nzola e Bonfanti, dentro Angori e Tramoni per il Pisa.<\/p>\n<p><em><strong>73&#8242;\u00a0<\/strong><\/em><strong>GOOOOOOOOOOOOOL! Il Napoli passa nuovamente in vantaggio. Grande conclusione di Spinazzola.<\/strong><\/p>\n<p><strong>72&#8242;<\/strong>\u00a0Cross di Spinzzola, colpo di testa di Di Lorenzo, debole la conclusione.<\/p>\n<p><em><strong>68&#8242;\u00a0<\/strong><\/em>Ammonizione per Spinazzola per gamba tesa.<\/p>\n<p><em><strong>67&#8242;<\/strong><\/em>\u00a0Termina alta sopra la traversa la conclusione di De Bruyne.<\/p>\n<p><em><strong>66&#8242;<\/strong><\/em>\u00a0Giallo per Meister per fallo su Politano.<\/p>\n<p><strong>63&#8242;<\/strong>\u00a0Si salva il Pisa dopo una mischia in area di rigore, sugli sviluppi di calcio d&#8217;angolo.<\/p>\n<p><em><strong>61&#8242;<\/strong>\u00a0Doppio cambio per il Pisa. Fuori Leris e Moreo, per Cuadrado e Meister.<\/em><\/p>\n<p><em><strong>60&#8242;<\/strong><\/em>\u00a0Gol del Pisa. Nzola trasforma il calcio di rigore.<\/p>\n<p><em><strong>58&#8242;<\/strong><\/em>\u00a0Tiro di Lusuardi, fallo di mano di Beukema. Calcio di rigore per il Pisa dopo il check del Var.<\/p>\n<p><em><strong>57<\/strong><\/em>&#8216; Doppio cambio per il Napoli. Fuori Elmas e Gilmour, per Anguissa e Lobotka.<\/p>\n<p><strong>57&#8242;\u00a0<\/strong>Conclusione centrale di Akinsanmiro, para Meret. Calcio d&#8217;angolo per il Pisa.<\/p>\n<p><em><strong>55&#8242;<\/strong>\u00a0Occasione per il Pisa, 5 vs 5 ma \u00e8 mancata la conclusione da parte dei toscani.<\/em><\/p>\n<p><em><strong>54&#8242;<\/strong><\/em>\u00a0Triangolo tra Hojlund-Politano-McTominay, alta la conclusione dello scozzese.<\/p>\n<p><em><strong>53&#8242;\u00a0<\/strong><\/em>Alta la conclusione di Politano con il mancino.<\/p>\n<p><strong>52&#8242;<\/strong>\u00a0Recupero di Spinazzola, transizione positiva, l&#8217;esterno arriva fino in fondo, a mancare \u00e8 la precisione di Politano che non riesce a colpire bene il pallone che sarebbe potuto valere il raddopio.<\/p>\n<p><em><strong>50&#8242;\u00a0<\/strong><\/em>Giallo per Caracciolo, fallo su Hojlund.<\/p>\n<p><strong>49&#8242;\u00a0<\/strong>Tentativo del capitano Di Lorenzo sul lanco illuminante di De Bruyne, allontana Semper.<\/p>\n<p><strong>48<\/strong>&#8216; Ritmi spesso interrotti all&#8217;inizio del secondo tempo.<\/p>\n<p><em><strong>21.53\u00a0<\/strong><\/em>Riparte la<em>\u00a0<\/em>gara.<\/p>\n<p><em><strong>21.39\u00a0<\/strong><\/em>Il primo tempo si conclude con il punteggio di 1-0 per il Napoli in seguito al gol di Gilmour. Per larghi tratti si rivedono le difficolt\u00e0 a sfondare il blocco passo del Pisa, come contro il Cagliari. I nerazzurri, per\u00f2, oltre alle ripartenze sono riusciti ad essere pericolosi anche in qualche occasione manovrata. Verso la fine del primo tempo, ghiotta occasione avuta da Hojlund per consolidare il punteggio.<\/p>\n<p><strong>49&#8242;\u00a0\u00a0<\/strong>Finisce il primo tempo al Maradona.<\/p>\n<p><strong>49&#8242;\u00a0<\/strong>Hojlund recupera il pallone e parte in contropiede, sceglie di fare tutto da solo ed il tiro viene deviato in calcio d&#8217;angolo. In posizione ottimale sia McTominay che De Bruyne avrebbero preferito il passaggio per concludere in rete.<\/p>\n<p><strong>47&#8242;\u00a0<\/strong>Intervento di Meret sulla rovesciata di Canestrelli in area di rigore.<\/p>\n<p><strong>45&#8242; &#8211;<\/strong>\u00a04&#8242; di recupero<\/p>\n<p><strong>45&#8242;<\/strong>\u00a0Grande azione del Pisa e altrettanto bravo Meret sul tiro di Leris a pochi passi dalla porta.<\/p>\n<p><strong>39&#8242; GOOOOOL! Il Napoli passa in vantaggio con il tiro di Gilmour. Iniziativa di Spinazzola sulla sinistra, tiro di Gilmour con la deviazione vincente di Canestrelli.<\/strong><\/p>\n<p><strong>38<\/strong>&#8216; Tre passaggi ed il Pisa si trova sulla trequarti, debole la conclusione di\u00a0Akinsamiro<\/p>\n<p><strong>36&#8242;\u00a0<\/strong>Blocco basso del Pisa, ripartenze ma anche un po&#8217; di possesso. L&#8217;iniziativa sfuma, il pallone arriva a Meret.<\/p>\n<p><strong>33&#8242;\u00a0<\/strong>Solito scambio tra Di Lorenzo e Politano, il pallone si spegne ancora una volta tra le mani dell&#8217;estremo difensore del Pisa.<\/p>\n<p><strong>31&#8242;\u00a0<\/strong>Giro palla con pazienza del Napoli. Ancora Politano dentro per cercare Hojlund, il pallone viene afferrato da Semper.<\/p>\n<p><strong>26&#8242; Gol annullato al Napoli.<\/strong>\u00a0Imbucata per Hojlund in profondit\u00e0. Elmas ribadisce in rete sulla respinta di Semper, ma viene segnalata la posizione di fuorigioco del danese. Dalle immagini Var, soltanto una piccola parte di spalla era oltre la linea dei difensori.<\/p>\n<p><strong>24&#8242;<\/strong>\u00a0Sguscia Politano su tutto l&#8217;out di destra, il tiro di Elmas viene liberato da Caracciolo.<\/p>\n<p><strong>23&#8242;\u00a0<\/strong>Scambio Politano-Di Lorenzo, para Semper sul tiro del capitano.<\/p>\n<p><strong>21&#8242;\u00a0<\/strong>Il Napoli fraseggia, arriva da Politano sull&#8217;esterno per arrivare alla solita combinazione con McTominay. Sar\u00e0 calcio d&#8217;angolo.<\/p>\n<p><strong>18&#8242;\u00a0<\/strong>Calcio d&#8217;angolo Pisa, proteste dei giocatori ma Beukema tocca con il fianco ed il Napoli prova ad uscire.<\/p>\n<p><strong>15&#8242;<\/strong>\u00a0Calcio di punizione Pisa dalla distanza, facile preda per Meret.<\/p>\n<p><strong>13&#8242;\u00a0<\/strong>Calcio d&#8217;angolo Politano, il tiro di De Bruyne si spegne tra le braccia di Semper.<\/p>\n<p><strong>11&#8242;\u00a0<\/strong>Nessun rigore per il Pisa, prima dello step in foot di De Bruyne c&#8217;\u00e8 stato un tocco con la mano di Leris.<\/p>\n<p><strong>9&#8242;\u00a0<\/strong>Check in corso del Var per l&#8217;intervento di De Bruyne sul piede di Leris all&#8217;interno dell&#8217;area di rigore.<\/p>\n<p><strong>8&#8242;\u00a0<\/strong>Forcing del Pisa, Di Lorenzo di testa allontana il cross.<\/p>\n<p><strong>7&#8242;\u00a0<\/strong>Cross di Politano per McTominay, nel tentativo di rovesciata lo scozzese commette un fallo.<\/p>\n<p><strong>6&#8242;\u00a0<\/strong>Errore del Pisa in costruzione, impreciso Politano che non riesce a servire Hojlund in una posizione pericolosa.<\/p>\n<p><strong>5&#8242;<\/strong>\u00a0Passaggio impreciso di Gilmour, fallo di Elmas che ferma il contropiede.<\/p>\n<p><strong>3&#8242;<\/strong>\u00a0Il Napoli inizia a prendere campo e controllare il gioco.<\/p>\n<p><strong>1&#8242;\u00a0<\/strong>Pronti-via, il Pisa si lancia subito in avanti dopo il calcio d&#8217;inizio.<\/p>\n<p><strong>20.48 NAPOLI-PISA\u00a0<\/strong><strong>\u00c8 INIZIATA!<\/strong><\/p>\n<p>[Fonte:&#8217;TuttoNapoli&#8217;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Napoli vince ma quanta sofferenza nel finale. Gli azzurri si prendono la vetta solitaria e allungano sulle avversarie.<\/p>\n","protected":false},"author":8,"featured_media":22740,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-22739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1-150x150.png","medium":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1-300x147.png","medium_large":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1.png","large":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1.png","1536x1536":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1.png","2048x2048":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1.png"},"magazineBlocksPostAuthor":{"name":"Filippo Toscano","avatar":"https:\/\/secure.gravatar.com\/avatar\/56d35f2d1652dcf45a09c954ac964cf950e2e0d563a65d7a5a0b0e94a36fe133?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Il Napoli vince ma quanta sofferenza nel finale. Gli azzurri si prendono la vetta solitaria e allungano sulle avversarie.","magazineBlocksPostCategories":["News"],"magazineBlocksPostViewCount":185,"magazineBlocksPostReadTime":5,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1.png",760,372,false],"medium":["https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1-300x147.png",300,147,true],"thumbnail":["https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1-150x150.png",150,150,true]},"magazine_blocks_author":{"display_name":"Filippo Toscano","author_link":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/author\/filippo-toscano\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/56d35f2d1652dcf45a09c954ac964cf950e2e0d563a65d7a5a0b0e94a36fe133?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-5\">News<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Napoli-Pisa 3-2 (39&#039; Gilmour, 60&#039; Nzola, 73&#039; Spinazzola, 82&#039; Lucca, 90&#039; Lorran). - TuttoAzzurro.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/2025\/09\/22\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Napoli-Pisa 3-2 (39&#039; Gilmour, 60&#039; Nzola, 73&#039; Spinazzola, 82&#039; Lucca, 90&#039; Lorran). - TuttoAzzurro.it\" \/>\n<meta property=\"og:description\" content=\"Il Napoli vince ma quanta sofferenza nel finale. Gli azzurri si prendono la vetta solitaria e allungano sulle avversarie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/2025\/09\/22\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\/\" \/>\n<meta property=\"og:site_name\" content=\"TuttoAzzurro.it\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-22T21:10:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"372\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Filippo Toscano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1.png\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Filippo Toscano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/2025\\\/09\\\/22\\\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/2025\\\/09\\\/22\\\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\\\/\"},\"author\":{\"name\":\"Filippo Toscano\",\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/#\\\/schema\\\/person\\\/3736e10f01163a1b281cc1aea454684b\"},\"headline\":\"Napoli-Pisa 3-2 (39&#8242; Gilmour, 60&#8242; Nzola, 73&#8242; Spinazzola, 82&#8242; Lucca, 90&#8242; Lorran).\",\"datePublished\":\"2025-09-22T21:10:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/2025\\\/09\\\/22\\\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\\\/\"},\"wordCount\":918,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/2025\\\/09\\\/22\\\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/napoli_pisa_1.png\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/2025\\\/09\\\/22\\\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\\\/\",\"url\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/2025\\\/09\\\/22\\\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\\\/\",\"name\":\"Napoli-Pisa 3-2 (39' Gilmour, 60' Nzola, 73' Spinazzola, 82' Lucca, 90' Lorran). - TuttoAzzurro.it\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/2025\\\/09\\\/22\\\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/2025\\\/09\\\/22\\\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/napoli_pisa_1.png\",\"datePublished\":\"2025-09-22T21:10:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/2025\\\/09\\\/22\\\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/2025\\\/09\\\/22\\\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/2025\\\/09\\\/22\\\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/napoli_pisa_1.png\",\"contentUrl\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/napoli_pisa_1.png\",\"width\":760,\"height\":372},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/2025\\\/09\\\/22\\\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Napoli-Pisa 3-2 (39&#8242; Gilmour, 60&#8242; Nzola, 73&#8242; Spinazzola, 82&#8242; Lucca, 90&#8242; Lorran).\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/\",\"name\":\"TuttoAzzurro.it\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/#organization\",\"name\":\"TuttoAzzurro.it\",\"url\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/cropped-logo_tuttoAzzurro-Recuperato-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/cropped-logo_tuttoAzzurro-Recuperato-1-1.png\",\"width\":600,\"height\":280,\"caption\":\"TuttoAzzurro.it\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/#\\\/schema\\\/person\\\/3736e10f01163a1b281cc1aea454684b\",\"name\":\"Filippo Toscano\",\"url\":\"https:\\\/\\\/www.tuttoazzurro.it\\\/new\\\/wordpress\\\/author\\\/filippo-toscano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Napoli-Pisa 3-2 (39' Gilmour, 60' Nzola, 73' Spinazzola, 82' Lucca, 90' Lorran). - TuttoAzzurro.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/2025\/09\/22\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\/","og_locale":"it_IT","og_type":"article","og_title":"Napoli-Pisa 3-2 (39' Gilmour, 60' Nzola, 73' Spinazzola, 82' Lucca, 90' Lorran). - TuttoAzzurro.it","og_description":"Il Napoli vince ma quanta sofferenza nel finale. Gli azzurri si prendono la vetta solitaria e allungano sulle avversarie.","og_url":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/2025\/09\/22\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\/","og_site_name":"TuttoAzzurro.it","article_published_time":"2025-09-22T21:10:47+00:00","og_image":[{"width":760,"height":372,"url":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1.png","type":"image\/png"}],"author":"Filippo Toscano","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1.png","twitter_misc":{"Scritto da":"Filippo Toscano","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/2025\/09\/22\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\/#article","isPartOf":{"@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/2025\/09\/22\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\/"},"author":{"name":"Filippo Toscano","@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/#\/schema\/person\/3736e10f01163a1b281cc1aea454684b"},"headline":"Napoli-Pisa 3-2 (39&#8242; Gilmour, 60&#8242; Nzola, 73&#8242; Spinazzola, 82&#8242; Lucca, 90&#8242; Lorran).","datePublished":"2025-09-22T21:10:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/2025\/09\/22\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\/"},"wordCount":918,"publisher":{"@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/#organization"},"image":{"@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/2025\/09\/22\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1.png","articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/2025\/09\/22\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\/","url":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/2025\/09\/22\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\/","name":"Napoli-Pisa 3-2 (39' Gilmour, 60' Nzola, 73' Spinazzola, 82' Lucca, 90' Lorran). - TuttoAzzurro.it","isPartOf":{"@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/2025\/09\/22\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\/#primaryimage"},"image":{"@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/2025\/09\/22\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1.png","datePublished":"2025-09-22T21:10:47+00:00","breadcrumb":{"@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/2025\/09\/22\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tuttoazzurro.it\/new\/wordpress\/2025\/09\/22\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/2025\/09\/22\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\/#primaryimage","url":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1.png","contentUrl":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1.png","width":760,"height":372},{"@type":"BreadcrumbList","@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/2025\/09\/22\/napoli-pisa-3-2-39-gilmour-60-nzola-73-spinazzola-82-lucca-90-lorran\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Napoli-Pisa 3-2 (39&#8242; Gilmour, 60&#8242; Nzola, 73&#8242; Spinazzola, 82&#8242; Lucca, 90&#8242; Lorran)."}]},{"@type":"WebSite","@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/#website","url":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/","name":"TuttoAzzurro.it","description":"","publisher":{"@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/#organization","name":"TuttoAzzurro.it","url":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2020\/09\/cropped-logo_tuttoAzzurro-Recuperato-1-1.png","contentUrl":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2020\/09\/cropped-logo_tuttoAzzurro-Recuperato-1-1.png","width":600,"height":280,"caption":"TuttoAzzurro.it"},"image":{"@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/#\/schema\/person\/3736e10f01163a1b281cc1aea454684b","name":"Filippo Toscano","url":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/author\/filippo-toscano\/"}]}},"featured_image_urls":{"full":["https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1.png",760,372,false],"thumbnail":["https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1-150x150.png",150,150,true],"medium":["https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1-300x147.png",300,147,true],"medium_large":["https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1.png",640,313,false],"large":["https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1.png",640,313,false],"1536x1536":["https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1.png",760,372,false],"2048x2048":["https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-content\/uploads\/2025\/09\/napoli_pisa_1.png",760,372,false]},"author_info":{"display_name":"Filippo Toscano","author_link":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/author\/filippo-toscano\/"},"category_info":"<a href=\"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/category\/news\/\" rel=\"category tag\">News<\/a>","tag_info":"News","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-json\/wp\/v2\/posts\/22739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-json\/wp\/v2\/comments?post=22739"}],"version-history":[{"count":1,"href":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-json\/wp\/v2\/posts\/22739\/revisions"}],"predecessor-version":[{"id":22742,"href":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-json\/wp\/v2\/posts\/22739\/revisions\/22742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-json\/wp\/v2\/media\/22740"}],"wp:attachment":[{"href":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-json\/wp\/v2\/media?parent=22739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-json\/wp\/v2\/categories?post=22739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tuttoazzurro.it\/new\/wordpress\/wp-json\/wp\/v2\/tags?post=22739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}